{"id":109891,"date":"2020-06-09T05:47:11","date_gmt":"2020-06-09T05:47:11","guid":{"rendered":"https:\/\/www.rapidreliefteam.org\/shop\/"},"modified":"2020-09-20T09:33:48","modified_gmt":"2020-09-20T09:33:48","slug":"shop","status":"publish","type":"page","link":"https:\/\/rrtglobal.org\/de\/shop\/","title":{"rendered":"Shop"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/rrtglobal.org\/de\/shop\/\">Weiterlesen\u00a0\u2026<span class=\"screen-reader-text\"> from Shop<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":417,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-L9-content.php","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-109891","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shop - Rapid Relief Team<\/title>\n<meta name=\"description\" content=\"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rrtglobal.org\/de\/shop\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shop - Rapid Relief Team\" \/>\n<meta property=\"og:description\" content=\"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rrtglobal.org\/de\/shop\/\" \/>\n<meta property=\"og:site_name\" content=\"Rapid Relief Team\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-20T09:33:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rrtglobal.org\\\/de\\\/shop\\\/\",\"url\":\"https:\\\/\\\/rrtglobal.org\\\/de\\\/shop\\\/\",\"name\":\"Shop - Rapid Relief Team\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#website\"},\"datePublished\":\"2020-06-09T05:47:11+00:00\",\"dateModified\":\"2020-09-20T09:33:48+00:00\",\"description\":\"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rrtglobal.org\\\/de\\\/shop\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rrtglobal.org\\\/de\\\/shop\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rrtglobal.org\\\/de\\\/shop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Zuhause\",\"item\":\"https:\\\/\\\/rrtglobal.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/\",\"name\":\"Rapid Relief Team\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#organization\",\"name\":\"Rapid Relief Team\",\"url\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rrtglobal.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/5134-RRT-Logo-Full-Color-1.png\",\"contentUrl\":\"https:\\\/\\\/rrtglobal.org\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/5134-RRT-Logo-Full-Color-1.png\",\"width\":690,\"height\":256,\"caption\":\"Rapid Relief Team\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rrtglobal.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shop - Rapid Relief Team","description":"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rrtglobal.org\/de\/shop\/","og_locale":"de_DE","og_type":"article","og_title":"Shop - Rapid Relief Team","og_description":"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.","og_url":"https:\/\/rrtglobal.org\/de\/shop\/","og_site_name":"Rapid Relief Team","article_modified_time":"2020-09-20T09:33:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rrtglobal.org\/de\/shop\/","url":"https:\/\/rrtglobal.org\/de\/shop\/","name":"Shop - Rapid Relief Team","isPartOf":{"@id":"https:\/\/www.rrtglobal.org\/de\/#website"},"datePublished":"2020-06-09T05:47:11+00:00","dateModified":"2020-09-20T09:33:48+00:00","description":"Besuchen Sie unseren Shop und entdecken Sie unsere Kernproduktpalette, zu der auch unser globales Maskottchen Cookie geh\u00f6rt. Kaufen Sie bei RRT und wissen Sie, dass Sie Menschen in Not unterst\u00fctzen.","breadcrumb":{"@id":"https:\/\/rrtglobal.org\/de\/shop\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rrtglobal.org\/de\/shop\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rrtglobal.org\/de\/shop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Zuhause","item":"https:\/\/rrtglobal.org\/de\/"},{"@type":"ListItem","position":2,"name":"Shop"}]},{"@type":"WebSite","@id":"https:\/\/www.rrtglobal.org\/de\/#website","url":"https:\/\/www.rrtglobal.org\/de\/","name":"Rapid Relief Team","description":"","publisher":{"@id":"https:\/\/www.rrtglobal.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rrtglobal.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.rrtglobal.org\/de\/#organization","name":"Rapid Relief Team","url":"https:\/\/www.rrtglobal.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.rrtglobal.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/rrtglobal.org\/wp-content\/uploads\/2020\/07\/5134-RRT-Logo-Full-Color-1.png","contentUrl":"https:\/\/rrtglobal.org\/wp-content\/uploads\/2020\/07\/5134-RRT-Logo-Full-Color-1.png","width":690,"height":256,"caption":"Rapid Relief Team"},"image":{"@id":"https:\/\/www.rrtglobal.org\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/pages\/109891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/comments?post=109891"}],"version-history":[{"count":4,"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/pages\/109891\/revisions"}],"predecessor-version":[{"id":112902,"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/pages\/109891\/revisions\/112902"}],"wp:attachment":[{"href":"https:\/\/rrtglobal.org\/de\/wp-json\/wp\/v2\/media?parent=109891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}